{"id":293,"date":"2026-01-30T22:44:54","date_gmt":"2026-01-30T22:44:54","guid":{"rendered":"https:\/\/df-tour.de\/?page_id=293"},"modified":"2026-07-15T10:51:36","modified_gmt":"2026-07-15T10:51:36","slug":"impressum","status":"publish","type":"page","link":"https:\/\/dftour.de\/index.php\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"293\" class=\"elementor elementor-293\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7d086b e-flex e-con-boxed e-con e-parent\" data-id=\"c7d086b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-01f5146 e-con-full e-flex e-con e-child\" data-id=\"01f5146\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dafac7d e-con-full e-flex e-con e-child\" data-id=\"dafac7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6c893b elementor-widget elementor-widget-html\" data-id=\"c6c893b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!--\nDF Tour GmbH \u2013 Professionelles Impressum\nEinbau: Gesamten Inhalt in ein Elementor-HTML-Widget einf\u00fcgen.\nStand der Gestaltung: Juli 2026\nHinweis: Rechtliche Angaben regelm\u00e4\u00dfig mit Handelsregister, Genehmigungsurkunden\nund tats\u00e4chlichen Unternehmensdaten abgleichen.\n-->\n\n<style>\n  #df-impressum {\n    --df-blue: #244f97;\n    --df-dark: #102a55;\n    --df-gold: #f2a900;\n    --df-text: #1b2537;\n    --df-muted: #637086;\n    --df-bg: #f4f7fb;\n    --df-white: #ffffff;\n    --df-border: rgba(36, 79, 151, 0.14);\n    --df-shadow: 0 16px 42px rgba(16, 42, 85, 0.10);\n    --df-radius: 22px;\n    --df-width: 1120px;\n\n    width: 100%;\n    overflow: hidden;\n    color: var(--df-text);\n    background: var(--df-bg);\n    font-family: inherit;\n    line-height: 1.7;\n  }\n\n  #df-impressum *,\n  #df-impressum *::before,\n  #df-impressum *::after {\n    box-sizing: border-box;\n  }\n\n  #df-impressum a {\n    color: var(--df-blue);\n    text-decoration: none;\n    overflow-wrap: anywhere;\n  }\n\n  #df-impressum a:hover {\n    text-decoration: underline;\n  }\n\n  #df-impressum .dfi-container {\n    width: min(calc(100% - 40px), var(--df-width));\n    margin: 0 auto;\n  }\n\n  #df-impressum .dfi-hero {\n    position: relative;\n    padding: 105px 0 95px;\n    overflow: hidden;\n    color: var(--df-white);\n    background:\n      radial-gradient(circle at 83% 15%, rgba(242, 169, 0, 0.22), transparent 22%),\n      linear-gradient(120deg, #0b2349 0%, #244f97 100%);\n  }\n\n  #df-impressum .dfi-hero::after {\n    position: absolute;\n    right: -150px;\n    bottom: -220px;\n    width: 520px;\n    height: 520px;\n    border: 80px solid rgba(255,255,255,.06);\n    border-radius: 50%;\n    content: \"\";\n  }\n\n  #df-impressum .dfi-hero__inner {\n    position: relative;\n    z-index: 1;\n    max-width: 760px;\n  }\n\n  #df-impressum .dfi-kicker {\n    display: inline-flex;\n    align-items: center;\n    gap: 10px;\n    margin-bottom: 16px;\n    color: #dbe8ff;\n    font-size: .86rem;\n    font-weight: 800;\n    letter-spacing: .11em;\n    text-transform: uppercase;\n  }\n\n  #df-impressum .dfi-kicker::before {\n    width: 30px;\n    height: 3px;\n    border-radius: 999px;\n    background: var(--df-gold);\n    content: \"\";\n  }\n\n  #df-impressum h1 {\n    margin: 0 0 18px;\n    color: var(--df-white);\n    font-size: clamp(2.8rem, 7vw, 5.2rem);\n    line-height: 1;\n    letter-spacing: -.055em;\n  }\n\n  #df-impressum .dfi-hero p {\n    max-width: 680px;\n    margin: 0;\n    color: rgba(255,255,255,.82);\n    font-size: clamp(1rem, 2vw, 1.18rem);\n  }\n\n  #df-impressum .dfi-main {\n    padding: 72px 0 90px;\n  }\n\n  #df-impressum .dfi-grid {\n    display: grid;\n    grid-template-columns: repeat(2, minmax(0, 1fr));\n    gap: 22px;\n    align-items: stretch;\n  }\n\n  #df-impressum .dfi-card {\n    padding: clamp(25px, 4vw, 36px);\n    border: 1px solid var(--df-border);\n    border-radius: var(--df-radius);\n    background: var(--df-white);\n    box-shadow: var(--df-shadow);\n  }\n\n  #df-impressum .dfi-card--wide {\n    grid-column: 1 \/ -1;\n  }\n\n  #df-impressum .dfi-card__head {\n    display: flex;\n    align-items: center;\n    gap: 14px;\n    margin-bottom: 21px;\n  }\n\n  #df-impressum .dfi-icon {\n    width: 48px;\n    height: 48px;\n    flex: 0 0 48px;\n    display: grid;\n    place-items: center;\n    border-radius: 15px;\n    color: var(--df-blue);\n    background: rgba(36, 79, 151, .09);\n  }\n\n  #df-impressum .dfi-icon svg {\n    width: 25px;\n    height: 25px;\n  }\n\n  #df-impressum h2 {\n    margin: 0;\n    color: var(--df-dark);\n    font-size: clamp(1.25rem, 2.5vw, 1.65rem);\n    line-height: 1.25;\n  }\n\n  #df-impressum h3 {\n    margin: 28px 0 8px;\n    color: var(--df-dark);\n    font-size: 1.08rem;\n  }\n\n  #df-impressum p {\n    margin: 0 0 13px;\n  }\n\n  #df-impressum p:last-child {\n    margin-bottom: 0;\n  }\n\n  #df-impressum .dfi-company {\n    margin-bottom: 13px;\n    color: var(--df-dark);\n    font-size: 1.18rem;\n    font-weight: 800;\n  }\n\n  #df-impressum .dfi-label {\n    display: block;\n    margin-bottom: 3px;\n    color: var(--df-muted);\n    font-size: .82rem;\n    font-weight: 800;\n    letter-spacing: .06em;\n    text-transform: uppercase;\n  }\n\n  #df-impressum .dfi-detail {\n    margin-bottom: 18px;\n  }\n\n  #df-impressum .dfi-detail:last-child {\n    margin-bottom: 0;\n  }\n\n  #df-impressum .dfi-contact-list {\n    display: grid;\n    gap: 13px;\n    margin: 0;\n    padding: 0;\n    list-style: none;\n  }\n\n  #df-impressum .dfi-contact-list li {\n    display: flex;\n    align-items: flex-start;\n    gap: 11px;\n  }\n\n  #df-impressum .dfi-contact-list svg {\n    width: 20px;\n    height: 20px;\n    flex: 0 0 20px;\n    margin-top: 4px;\n    color: var(--df-blue);\n  }\n\n  #df-impressum .dfi-note {\n    margin-top: 26px;\n    padding: 19px 21px;\n    border-left: 4px solid var(--df-gold);\n    border-radius: 0 15px 15px 0;\n    color: var(--df-muted);\n    background: #fffaf0;\n  }\n\n  #df-impressum .dfi-note strong {\n    color: var(--df-dark);\n  }\n\n  #df-impressum .dfi-legal {\n    color: var(--df-muted);\n  }\n\n  #df-impressum .dfi-footer-note {\n    margin-top: 24px;\n    padding: 20px 24px;\n    border: 1px solid var(--df-border);\n    border-radius: 17px;\n    color: var(--df-muted);\n    background: rgba(255,255,255,.68);\n    font-size: .94rem;\n  }\n\n  @media (max-width: 760px) {\n    #df-impressum .dfi-container {\n      width: min(calc(100% - 26px), var(--df-width));\n    }\n\n    #df-impressum .dfi-hero {\n      padding: 82px 0 75px;\n    }\n\n    #df-impressum .dfi-main {\n      padding: 52px 0 65px;\n    }\n\n    #df-impressum .dfi-grid {\n      grid-template-columns: 1fr;\n    }\n\n    #df-impressum .dfi-card--wide {\n      grid-column: auto;\n    }\n  }\n<\/style>\n\n<section id=\"df-impressum\" aria-labelledby=\"dfi-title\">\n\n  <header class=\"dfi-hero\">\n    <div class=\"dfi-container\">\n      <div class=\"dfi-hero__inner\">\n        <div class=\"dfi-kicker\">Rechtliche Anbieterkennzeichnung<\/div>\n        <h1 id=\"dfi-title\">Impressum<\/h1>\n        <p>\n          Angaben gem\u00e4\u00df \u00a7 5 Digitale-Dienste-Gesetz (DDG) sowie,\n          soweit einschl\u00e4gig, gem\u00e4\u00df \u00a7 18 Medienstaatsvertrag (MStV).\n        <\/p>\n      <\/div>\n    <\/div>\n  <\/header>\n\n  <main class=\"dfi-main\">\n    <div class=\"dfi-container\">\n      <div class=\"dfi-grid\">\n\n        <section class=\"dfi-card\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M4 21a1 1 0 0 1-1-1V8.8a2 2 0 0 1 1-1.7l7-4.4a2 2 0 0 1 2.1 0l7 4.4a2 2 0 0 1 .9 1.7V20a1 1 0 0 1-1 1h-6v-6h-4v6H4Zm1-2h3v-6h8v6h3V8.8l-7-4.4-7 4.4V19Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Diensteanbieter<\/h2>\n          <\/div>\n\n          <div class=\"dfi-company\">D.F. Tour GmbH<\/div>\n          <p>\n            Humbserstra\u00dfe 21<br>\n            90763 F\u00fcrth<br>\n            Deutschland\n          <\/p>\n        <\/section>\n\n        <section class=\"dfi-card\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M12 2a5 5 0 1 1 0 10 5 5 0 0 1 0-10Zm0 2a3 3 0 1 0 0 6 3 3 0 0 0 0-6Zm-7 18a1 1 0 0 1-1-1v-2a6 6 0 0 1 6-6h4a6 6 0 0 1 6 6v2a1 1 0 1 1-2 0v-2a4 4 0 0 0-4-4h-4a4 4 0 0 0-4 4v2a1 1 0 0 1-1 1Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Vertretungsberechtigte Gesch\u00e4ftsf\u00fchrung<\/h2>\n          <\/div>\n\n          <p>Eduard Deines<\/p>\n          <p>Ali Fuat Yildiz<\/p>\n        <\/section>\n\n        <section class=\"dfi-card\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M5 3h14a2 2 0 0 1 2 2v14a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2Zm0 2v2.2l7 4.7 7-4.7V5H5Zm14 4.6-6.4 4.3a1 1 0 0 1-1.2 0L5 9.6V19h14V9.6Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Kontakt<\/h2>\n          <\/div>\n\n          <ul class=\"dfi-contact-list\">\n            <li>\n              <svg viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n                <path fill=\"currentColor\" d=\"M6.6 2h2.8a2 2 0 0 1 2 1.7l.5 3.1a2 2 0 0 1-.6 1.8L9.6 10a14 14 0 0 0 4.4 4.4l1.4-1.7a2 2 0 0 1 1.8-.6l3.1.5a2 2 0 0 1 1.7 2v2.8a4.6 4.6 0 0 1-5 4.6A16.5 16.5 0 0 1 2 7a4.6 4.6 0 0 1 4.6-5Z\"\/>\n              <\/svg>\n              <span>\n                Telefon Eduard Deines:<br>\n                <a href=\"tel:+4917661508285\">+49 176 6150 8285<\/a>\n              <\/span>\n            <\/li>\n            <li>\n              <svg viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n                <path fill=\"currentColor\" d=\"M6.6 2h2.8a2 2 0 0 1 2 1.7l.5 3.1a2 2 0 0 1-.6 1.8L9.6 10a14 14 0 0 0 4.4 4.4l1.4-1.7a2 2 0 0 1 1.8-.6l3.1.5a2 2 0 0 1 1.7 2v2.8a4.6 4.6 0 0 1-5 4.6A16.5 16.5 0 0 1 2 7a4.6 4.6 0 0 1 4.6-5Z\"\/>\n              <\/svg>\n              <span>\n                Telefon Ali Fuat Yildiz:<br>\n                <a href=\"tel:+4917632986914\">+49 176 3298 6914<\/a>\n              <\/span>\n            <\/li>\n            <li>\n              <svg viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n                <path fill=\"currentColor\" d=\"M5 3h14a2 2 0 0 1 2 2v14a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V5a2 2 0 0 1 2-2Zm0 2v2.2l7 4.7 7-4.7V5H5Zm14 4.6-6.4 4.3a1 1 0 0 1-1.2 0L5 9.6V19h14V9.6Z\"\/>\n              <\/svg>\n              <span>\n                E-Mail:<br>\n                <a href=\"mailto:info@df-tour.de\">info@df-tour.de<\/a>\n              <\/span>\n            <\/li>\n          <\/ul>\n        <\/section>\n\n        <section class=\"dfi-card\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M4 3h16a1 1 0 0 1 1 1v4a1 1 0 0 1-1 1h-1v10h1a1 1 0 1 1 0 2H4a1 1 0 1 1 0-2h1V9H4a1 1 0 0 1-1-1V4a1 1 0 0 1 1-1Zm1 2v2h14V5H5Zm2 4v10h2V9H7Zm4 0v10h2V9h-2Zm4 0v10h2V9h-2Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Register und Steuerangaben<\/h2>\n          <\/div>\n\n          <div class=\"dfi-detail\">\n            <span class=\"dfi-label\">Registergericht<\/span>\n            Amtsgericht F\u00fcrth\n          <\/div>\n\n          <div class=\"dfi-detail\">\n            <span class=\"dfi-label\">Handelsregisternummer<\/span>\n            HRB 17730\n          <\/div>\n\n          <div class=\"dfi-detail\">\n            <span class=\"dfi-label\">Umsatzsteuer-Identifikationsnummer<\/span>\n            DE326958046\n          <\/div>\n        <\/section>\n\n        <section class=\"dfi-card dfi-card--wide\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M12 2 4 5v6c0 5.2 3.4 9.9 8 11 4.6-1.1 8-5.8 8-11V5l-8-3Zm0 2.1L18 6.3V11c0 4-2.5 7.8-6 8.9C8.5 18.8 6 15 6 11V6.3l6-2.2Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Zust\u00e4ndige Genehmigungs- und Aufsichtsbeh\u00f6rde<\/h2>\n          <\/div>\n\n          <p>\n            Regierung von Mittelfranken<br>\n            Sachgebiet 23 \u2013 Stra\u00dfen- und Schienenverkehr<br>\n            Promenade 27<br>\n            91522 Ansbach\n          <\/p>\n\n          <p>\n            E-Mail:\n            <a href=\"mailto:oepnv@reg-mfr.bayern.de\">oepnv@reg-mfr.bayern.de<\/a>\n          <\/p>\n\n          <div class=\"dfi-note\">\n            <strong>Wichtiger Abgleich:<\/strong>\n            Die Beh\u00f6rdenangabe sollte vor Ver\u00f6ffentlichung mit der f\u00fcr die D.F. Tour GmbH\n            tats\u00e4chlich erteilten Genehmigung beziehungsweise Gemeinschaftslizenz abgeglichen\n            werden. Ma\u00dfgeblich ist die in der Genehmigungsurkunde genannte Beh\u00f6rde.\n          <\/div>\n        <\/section>\n\n        <section class=\"dfi-card dfi-card--wide\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M6 2h9l5 5v15H6a2 2 0 0 1-2-2V4a2 2 0 0 1 2-2Zm8 2H6v16h12V8h-4V4Zm2 1.4V6h.6L16 5.4ZM8 11h8a1 1 0 1 1 0 2H8a1 1 0 1 1 0-2Zm0 4h8a1 1 0 1 1 0 2H8a1 1 0 1 1 0-2Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Verantwortlich f\u00fcr redaktionelle Inhalte<\/h2>\n          <\/div>\n\n          <p>\n            Soweit auf dieser Website journalistisch-redaktionell gestaltete Inhalte\n            angeboten werden, verantwortlich gem\u00e4\u00df \u00a7 18 Abs. 2 MStV:\n          <\/p>\n\n          <p>\n            Eduard Deines<br>\n            Humbserstra\u00dfe 21<br>\n            90763 F\u00fcrth\n          <\/p>\n        <\/section>\n\n        <section class=\"dfi-card dfi-card--wide\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M12 2a10 10 0 1 1 0 20 10 10 0 0 1 0-20Zm0 2a8 8 0 1 0 0 16 8 8 0 0 0 0-16Zm0 3a1 1 0 0 1 1 1v3.6l2.6 1.5a1 1 0 1 1-1 1.8l-3.1-1.8a1 1 0 0 1-.5-.9V8a1 1 0 0 1 1-1Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Verbraucherstreitbeilegung<\/h2>\n          <\/div>\n\n          <p>\n            Die D.F. Tour GmbH ist nicht bereit und nicht verpflichtet, an\n            Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle\n            teilzunehmen.\n          <\/p>\n        <\/section>\n\n        <section class=\"dfi-card dfi-card--wide dfi-legal\">\n          <div class=\"dfi-card__head\">\n            <div class=\"dfi-icon\" aria-hidden=\"true\">\n              <svg viewBox=\"0 0 24 24\">\n                <path fill=\"currentColor\" d=\"M12 2a10 10 0 1 1 0 20 10 10 0 0 1 0-20Zm0 2a8 8 0 1 0 0 16 8 8 0 0 0 0-16Zm0 6a1 1 0 0 1 1 1v5a1 1 0 1 1-2 0v-5a1 1 0 0 1 1-1Zm0-3a1.2 1.2 0 1 1 0 2.4A1.2 1.2 0 0 1 12 7Z\"\/>\n              <\/svg>\n            <\/div>\n            <h2>Haftungs- und Urheberrechtshinweise<\/h2>\n          <\/div>\n\n          <h3>Inhalte dieser Website<\/h3>\n          <p>\n            Die Inhalte dieser Website werden mit angemessener Sorgfalt erstellt\n            und gepflegt. Eine Gew\u00e4hr f\u00fcr die jederzeitige Richtigkeit,\n            Vollst\u00e4ndigkeit und Aktualit\u00e4t s\u00e4mtlicher Inhalte kann jedoch nicht\n            \u00fcbernommen werden. Gesetzlich zwingende Haftungsregelungen bleiben\n            unber\u00fchrt.\n          <\/p>\n\n          <h3>Externe Links<\/h3>\n          <p>\n            Diese Website kann Links zu externen Websites Dritter enthalten. Auf\n            deren aktuelle und zuk\u00fcnftige Inhalte hat die D.F. Tour GmbH keinen\n            beherrschenden Einfluss. F\u00fcr die Inhalte der verlinkten Seiten ist der\n            jeweilige Anbieter oder Betreiber verantwortlich. Werden konkrete\n            Rechtsverletzungen bekannt, werden entsprechende Links nach Pr\u00fcfung\n            entfernt.\n          <\/p>\n\n          <h3>Urheberrecht<\/h3>\n          <p>\n            Die auf dieser Website ver\u00f6ffentlichten Inhalte und Werke unterliegen\n            dem deutschen Urheberrecht, soweit nicht Rechte Dritter ausgewiesen\n            sind. Jede \u00fcber die gesetzlich erlaubte Nutzung hinausgehende\n            Vervielf\u00e4ltigung, Bearbeitung, Verbreitung oder sonstige Verwertung\n            bedarf der vorherigen Zustimmung des jeweiligen Rechteinhabers.\n          <\/p>\n        <\/section>\n\n      <\/div>\n\n      <div class=\"dfi-footer-note\">\n        Stand: Juli 2026. \u00c4nderungen bei Gesch\u00e4ftsf\u00fchrung, Anschrift,\n        Kommunikationsdaten, Registerangaben, Umsatzsteuer-ID oder\n        Genehmigungsbeh\u00f6rde m\u00fcssen unverz\u00fcglich im Impressum aktualisiert werden.\n      <\/div>\n    <\/div>\n  <\/main>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-efccd83 e-con-full e-flex e-con e-child\" data-id=\"efccd83\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rechtliche Anbieterkennzeichnung Impressum Angaben gem\u00e4\u00df \u00a7 5 Digitale-Dienste-Gesetz (DDG) sowie, soweit einschl\u00e4gig, gem\u00e4\u00df \u00a7 18 Medienstaatsvertrag (MStV). Diensteanbieter D.F. Tour GmbH Humbserstra\u00dfe 21 90763 F\u00fcrth Deutschland Vertretungsberechtigte Gesch\u00e4ftsf\u00fchrung Eduard Deines Ali Fuat Yildiz Kontakt Telefon Eduard Deines: +49 176 6150 8285 Telefon Ali Fuat Yildiz: +49 176 3298 6914 E-Mail: info@df-tour.de Register und Steuerangaben Registergericht [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-builder.php","meta":{"footnotes":""},"class_list":["post-293","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/pages\/293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/comments?post=293"}],"version-history":[{"count":10,"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/pages\/293\/revisions"}],"predecessor-version":[{"id":1294,"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/pages\/293\/revisions\/1294"}],"wp:attachment":[{"href":"https:\/\/dftour.de\/index.php\/wp-json\/wp\/v2\/media?parent=293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}